{"id":826,"count":4,"description":"","link":"https:\/\/pasedo.pl\/en\/kategorie\/marcegaglia-na-zawias-70-en-2\/","name":"Marcegaglia for 70mm hinge","slug":"marcegaglia-na-zawias-70-en-2","taxonomy":"product-categories","parent":812,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Archiwa Marcegaglia for 70mm hinge - Pasedo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pasedo.pl\/en\/kategorie\/marcegaglia-na-zawias-70-en-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archiwa Marcegaglia for 70mm hinge - Pasedo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pasedo.pl\/en\/kategorie\/marcegaglia-na-zawias-70-en-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Pasedo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/pasedo.pl\/en\/kategorie\/marcegaglia-na-zawias-70-en-2\/\",\"url\":\"https:\/\/pasedo.pl\/en\/kategorie\/marcegaglia-na-zawias-70-en-2\/\",\"name\":\"Archiwa Marcegaglia for 70mm hinge - Pasedo\",\"isPartOf\":{\"@id\":\"https:\/\/pasedo.pl\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/pasedo.pl\/en\/kategorie\/marcegaglia-na-zawias-70-en-2\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pasedo.pl\/en\/kategorie\/marcegaglia-na-zawias-70-en-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/pasedo.pl\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/pasedo.pl\/en\/product\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"End caps\",\"item\":\"https:\/\/pasedo.pl\/en\/kategorie\/okucia-en\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Side end caps for Marcegaglia panels 0,7mm\",\"item\":\"https:\/\/pasedo.pl\/en\/kategorie\/marcegaglia-okucia-boczne-garazowe-07mm-en\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Marcegaglia for 70mm hinge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pasedo.pl\/en\/#website\",\"url\":\"https:\/\/pasedo.pl\/en\/\",\"name\":\"Pasedo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/pasedo.pl\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pasedo.pl\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pasedo.pl\/en\/#organization\",\"name\":\"Pasedo\",\"url\":\"https:\/\/pasedo.pl\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/pasedo.pl\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pasedo.pl\/wp-content\/uploads\/2021\/12\/logo-2.png\",\"contentUrl\":\"https:\/\/pasedo.pl\/wp-content\/uploads\/2021\/12\/logo-2.png\",\"width\":324,\"height\":74,\"caption\":\"Pasedo\"},\"image\":{\"@id\":\"https:\/\/pasedo.pl\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/pl.linkedin.com\/company\/pasedo\",\"https:\/\/www.facebook.com\/pasedozawiercie\/?locale=pl_PL\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archiwa Marcegaglia for 70mm hinge - Pasedo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pasedo.pl\/en\/kategorie\/marcegaglia-na-zawias-70-en-2\/","og_locale":"en_US","og_type":"article","og_title":"Archiwa Marcegaglia for 70mm hinge - Pasedo","og_url":"https:\/\/pasedo.pl\/en\/kategorie\/marcegaglia-na-zawias-70-en-2\/","og_site_name":"Pasedo","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/pasedo.pl\/en\/kategorie\/marcegaglia-na-zawias-70-en-2\/","url":"https:\/\/pasedo.pl\/en\/kategorie\/marcegaglia-na-zawias-70-en-2\/","name":"Archiwa Marcegaglia for 70mm hinge - Pasedo","isPartOf":{"@id":"https:\/\/pasedo.pl\/en\/#website"},"breadcrumb":{"@id":"https:\/\/pasedo.pl\/en\/kategorie\/marcegaglia-na-zawias-70-en-2\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/pasedo.pl\/en\/kategorie\/marcegaglia-na-zawias-70-en-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pasedo.pl\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/pasedo.pl\/en\/product\/"},{"@type":"ListItem","position":3,"name":"End caps","item":"https:\/\/pasedo.pl\/en\/kategorie\/okucia-en\/"},{"@type":"ListItem","position":4,"name":"Side end caps for Marcegaglia panels 0,7mm","item":"https:\/\/pasedo.pl\/en\/kategorie\/marcegaglia-okucia-boczne-garazowe-07mm-en\/"},{"@type":"ListItem","position":5,"name":"Marcegaglia for 70mm hinge"}]},{"@type":"WebSite","@id":"https:\/\/pasedo.pl\/en\/#website","url":"https:\/\/pasedo.pl\/en\/","name":"Pasedo","description":"","publisher":{"@id":"https:\/\/pasedo.pl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pasedo.pl\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pasedo.pl\/en\/#organization","name":"Pasedo","url":"https:\/\/pasedo.pl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pasedo.pl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/pasedo.pl\/wp-content\/uploads\/2021\/12\/logo-2.png","contentUrl":"https:\/\/pasedo.pl\/wp-content\/uploads\/2021\/12\/logo-2.png","width":324,"height":74,"caption":"Pasedo"},"image":{"@id":"https:\/\/pasedo.pl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pl.linkedin.com\/company\/pasedo","https:\/\/www.facebook.com\/pasedozawiercie\/?locale=pl_PL"]}]}},"_links":{"self":[{"href":"https:\/\/pasedo.pl\/en\/wp-json\/wp\/v2\/product-categories\/826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pasedo.pl\/en\/wp-json\/wp\/v2\/product-categories"}],"about":[{"href":"https:\/\/pasedo.pl\/en\/wp-json\/wp\/v2\/taxonomies\/product-categories"}],"up":[{"embeddable":true,"href":"https:\/\/pasedo.pl\/en\/wp-json\/wp\/v2\/product-categories\/812"}]}}