{"id":876,"count":4,"description":"","link":"https:\/\/pasedo.pl\/it\/kategorie\/marcegaglia-na-zawias-70-it\/","name":"MARCEGAGLIA per cerniera 70","slug":"marcegaglia-na-zawias-70-it","taxonomy":"product-categories","parent":866,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Archiwa MARCEGAGLIA per cerniera 70 - Pasedo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pasedo.pl\/it\/kategorie\/marcegaglia-na-zawias-70-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archiwa MARCEGAGLIA per cerniera 70 - Pasedo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pasedo.pl\/it\/kategorie\/marcegaglia-na-zawias-70-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Pasedo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/pasedo.pl\/it\/kategorie\/marcegaglia-na-zawias-70-it\/\",\"url\":\"https:\/\/pasedo.pl\/it\/kategorie\/marcegaglia-na-zawias-70-it\/\",\"name\":\"Archiwa MARCEGAGLIA per cerniera 70 - Pasedo\",\"isPartOf\":{\"@id\":\"https:\/\/pasedo.pl\/it\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/pasedo.pl\/it\/kategorie\/marcegaglia-na-zawias-70-it\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pasedo.pl\/it\/kategorie\/marcegaglia-na-zawias-70-it\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/pasedo.pl\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\/\/pasedo.pl\/it\/product\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cartella laterale\",\"item\":\"https:\/\/pasedo.pl\/it\/kategorie\/okucia-it\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Cartella laterale Marcegaglia 0,7mm\",\"item\":\"https:\/\/pasedo.pl\/it\/kategorie\/cartella-laterale-marcegaglia-07mm\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"MARCEGAGLIA per cerniera 70\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pasedo.pl\/it\/#website\",\"url\":\"https:\/\/pasedo.pl\/it\/\",\"name\":\"Pasedo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/pasedo.pl\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pasedo.pl\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pasedo.pl\/it\/#organization\",\"name\":\"Pasedo\",\"url\":\"https:\/\/pasedo.pl\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/pasedo.pl\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pasedo.pl\/wp-content\/uploads\/2021\/12\/logo-2.png\",\"contentUrl\":\"https:\/\/pasedo.pl\/wp-content\/uploads\/2021\/12\/logo-2.png\",\"width\":324,\"height\":74,\"caption\":\"Pasedo\"},\"image\":{\"@id\":\"https:\/\/pasedo.pl\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/pl.linkedin.com\/company\/pasedo\",\"https:\/\/www.facebook.com\/pasedozawiercie\/?locale=pl_PL\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archiwa MARCEGAGLIA per cerniera 70 - Pasedo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pasedo.pl\/it\/kategorie\/marcegaglia-na-zawias-70-it\/","og_locale":"it_IT","og_type":"article","og_title":"Archiwa MARCEGAGLIA per cerniera 70 - Pasedo","og_url":"https:\/\/pasedo.pl\/it\/kategorie\/marcegaglia-na-zawias-70-it\/","og_site_name":"Pasedo","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/pasedo.pl\/it\/kategorie\/marcegaglia-na-zawias-70-it\/","url":"https:\/\/pasedo.pl\/it\/kategorie\/marcegaglia-na-zawias-70-it\/","name":"Archiwa MARCEGAGLIA per cerniera 70 - Pasedo","isPartOf":{"@id":"https:\/\/pasedo.pl\/it\/#website"},"breadcrumb":{"@id":"https:\/\/pasedo.pl\/it\/kategorie\/marcegaglia-na-zawias-70-it\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/pasedo.pl\/it\/kategorie\/marcegaglia-na-zawias-70-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pasedo.pl\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/pasedo.pl\/it\/product\/"},{"@type":"ListItem","position":3,"name":"Cartella laterale","item":"https:\/\/pasedo.pl\/it\/kategorie\/okucia-it\/"},{"@type":"ListItem","position":4,"name":"Cartella laterale Marcegaglia 0,7mm","item":"https:\/\/pasedo.pl\/it\/kategorie\/cartella-laterale-marcegaglia-07mm\/"},{"@type":"ListItem","position":5,"name":"MARCEGAGLIA per cerniera 70"}]},{"@type":"WebSite","@id":"https:\/\/pasedo.pl\/it\/#website","url":"https:\/\/pasedo.pl\/it\/","name":"Pasedo","description":"","publisher":{"@id":"https:\/\/pasedo.pl\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pasedo.pl\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/pasedo.pl\/it\/#organization","name":"Pasedo","url":"https:\/\/pasedo.pl\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/pasedo.pl\/it\/#\/schema\/logo\/image\/","url":"https:\/\/pasedo.pl\/wp-content\/uploads\/2021\/12\/logo-2.png","contentUrl":"https:\/\/pasedo.pl\/wp-content\/uploads\/2021\/12\/logo-2.png","width":324,"height":74,"caption":"Pasedo"},"image":{"@id":"https:\/\/pasedo.pl\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pl.linkedin.com\/company\/pasedo","https:\/\/www.facebook.com\/pasedozawiercie\/?locale=pl_PL"]}]}},"_links":{"self":[{"href":"https:\/\/pasedo.pl\/it\/wp-json\/wp\/v2\/product-categories\/876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pasedo.pl\/it\/wp-json\/wp\/v2\/product-categories"}],"about":[{"href":"https:\/\/pasedo.pl\/it\/wp-json\/wp\/v2\/taxonomies\/product-categories"}],"up":[{"embeddable":true,"href":"https:\/\/pasedo.pl\/it\/wp-json\/wp\/v2\/product-categories\/866"}]}}